{"id":232,"date":"2021-08-02T18:02:32","date_gmt":"2021-08-02T18:02:32","guid":{"rendered":"https:\/\/oneedenchiringuito.com\/?page_id=232"},"modified":"2021-08-03T07:46:42","modified_gmt":"2021-08-03T07:46:42","slug":"terminos-y-condiciones","status":"publish","type":"page","link":"https:\/\/oneedenchiringuito.com\/es\/terminos-y-condiciones\/","title":{"rendered":"T\u00e9rminos y condiciones"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">En cumplimiento del deber de informaci\u00f3n estipulado en el art\u00edculo 10 de la Ley 34\/2002 de 11 de julio de Servicios de la Sociedad de la Informaci\u00f3n y de Comercio Electr\u00f3nico, One Eden Hotel &amp; Beach Club SL (en adelante, \u201cOne Eden Chiringuito\u201d) y en calidad de titular del Sitio Web <a href=\"http:\/\/www.oneedenchiringuito.com\">www.oneedenchiringuito.com<\/a> , procede a comunicar los datos identificativos exigidos por la referida norma:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Denominaci\u00f3n social:<\/strong> One Eden Hotel &amp; Beach Club SL Domicilio social: Plaza de Bulevar, Edificio B, Local 12, 1\u00aa Planta, Oficinas 1A y 1B, CP: 29649, La Cala de Mijas, M\u00e1laga<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>CIF:<\/strong> ES- B93725489<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Direcci\u00f3n de correo electr\u00f3nico:<\/strong> <a href=\"mailto:legal@oneeden.es\">legal@oneeden.es<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Datos de inscripci\u00f3n en el Registro Mercantil de M\u00e1laga:<\/strong> Hoja MA- 153888, Tomo 5904, folio 175.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La presente informaci\u00f3n conforma y regula las condiciones de uso, las limitaciones de responsabilidad y las obligaciones que, los usuarios del Sitio Web que se publica bajo el nombre de dominio <a href=\"http:\/\/www.onedenchiringuito.com\">www.onedenchiringuito.com<\/a>, asumen y se comprometen a respetar.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Condiciones de uso<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">La mera utilizaci\u00f3n del Sitio Web supone la condici\u00f3n de usuario del mismo, ya sea persona f\u00edsica o jur\u00eddica, e implica de forma preceptiva la plena aceptaci\u00f3n, sin reservas, de todas las cl\u00e1usulas y condiciones establecidas en el Protocolo de T\u00e9rminos y Condiciones. En caso de que el usuario final no estuviera de acuerdo con las cl\u00e1usulas y condiciones de estos T\u00e9rminos y Condiciones, deber\u00e1 abstenerse de utilizar este Sitio Web.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Estos T\u00e9rminos y Condiciones est\u00e1n sujetos a cambios y a actualizaciones, lo que puede suponer que la versi\u00f3n publicada por One Eden Chiringuito puede ser diferente en cada momento en que el usuario acceda al Sitio Web. De esta forma, el usuario deber\u00e1 leer los T\u00e9rminos y Condiciones cada vez que acceda al Sitio Web.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A trav\u00e9s del Sitio Web, One Eden Chiringuito facilita a los usuarios finales el acceso y la utilizaci\u00f3n de diferentes contenidos publicados a trav\u00e9s de Internet por One Eden Chiringuito o por terceros autorizados.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El usuario final est\u00e1 obligado y se compromete a hacer un uso del Sitio Web y de los contenidos que en \u00e9l se incluyen, de conformidad con la normativa vigente, as\u00ed como con las normas de convivencia, la moral y las buenas costumbres generalmente aceptadas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A tal efecto, el usuario final se obliga y compromete a no utilizar cualquiera de los contenidos incluidos en el Sitio Web con fines il\u00edcitos, de mala fe, o prohibidos expresamente en los T\u00e9rminos y Condiciones o en la normativa vigente, o con fines que supongan la lesi\u00f3n de los derechos e intereses de terceros o que, de cualquier manera, puedan deteriorar, sobrecargar, inutilizar, da\u00f1ar o impedir la normal utilizaci\u00f3n y acceso a los contenidos del Sitio Web, los equipos inform\u00e1ticos, documentos, archivos o cualquier tipo de contenido almacenado en los equipos inform\u00e1ticos propios o contratados por One Eden Chiringuito, de otros usuarios o de cualquier otro usuario de Internet.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">De conformidad con todo ello, el usuario final no podr\u00e1:<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>Reproducir, copiar, distribuir, poner a disposici\u00f3n o comunicar p\u00fablicamente, transformar o modificar los contenidos del Sitio Web, a menos que One Eden Chiringuito as\u00ed lo haya autorizado de forma expl\u00edcita y por escrito, ya que es One Eden Chiringuito quien es el titular de los correspondientes derechos.<\/li><li>Suprimir, manipular, alterar de cualquier forma el copyright y dem\u00e1s datos identificativos de la reserva de derechos de One Eden Chiringuitoo de sus titulares, de identificadores digitales o de cualquier otro medio t\u00e9cnico establecido para su reconocimiento.<\/li><li>Menoscabar de cualquier manera el cr\u00e9dito de One Eden Chiringuito.<\/li><li>Infringir la normativa sobre secreto de las comunicaciones.<\/li><li>Constituir publicidad il\u00edcita, enga\u00f1osa o desleal.<\/li><\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">El usuario final deber\u00e1 abstenerse de obtener los contenidos incluidos en el Sitio Web, empleando para tal fin medios y procedimientos distintos de los que se hayan puesto a su disposici\u00f3n a este efecto, o en general, de los que se empleen normalmente en Internet a este efecto siempre que no entra\u00f1en un riesgo de da\u00f1o o inutilizaci\u00f3n del Sitio Web y de sus contenidos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Todos los contenidos que se incluyen en este Sitio Web se facilitan con la finalidad exclusivamente informativa, de modo que en ning\u00fan caso pueden servir de base para recursos o reclamaciones ni constituir fuente de derechos.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Propiedad intelectual<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Todas aquellos nombres comerciales, marcas o signos distintivos de cualquier tipo que se encuentren en el Sitio Web son propiedad de One Eden Chiringuito o, en su caso, de terceros que han autorizado su uso, sin que pueda entenderse que el acceso o uso del Sitio Web o de los contenidos que \u00e9ste incluye, otorguen al usuario derecho alguno sobre los mencionados nombres comerciales, marcas y logos distintivos y, sin que pueda entenderse que son cedidos al usuario ninguno de los derechos de explotaci\u00f3n existen o que pueden existir sobres los contenidos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Del mismo modo, los contenidos del Sitio Web son propiedad intelectual de One Eden Chiringuito, o de terceros en su caso, por lo que los derechos de propiedad intelectual son titularidad de One Eden Chiringuito o de aquellos terceros que han autorizado su uso a quienes corresponde el ejercicio exclusivo de los derechos de explotaci\u00f3n de los mismos en cualquier forma y, en especial, los derechos de reproducci\u00f3n, comunicaci\u00f3n p\u00fablica, distribuci\u00f3n y transformaci\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La utilizaci\u00f3n no autorizada de la informaci\u00f3n contenida en este Sitio Web, as\u00ed como la lesi\u00f3n de los derechos de propiedad intelectual o industrial de One Eden Chiringuito o de terceros incluidos en el Sitio Web que hayan cedido contenidos dar\u00e1 lugar a las responsabilidades legalmente establecidas.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Disponibilidad del Sitio Web<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">One Eden Chiringuito no garantiza la inexistencia de interrupciones o errores en el acceso al Sitio Web o a sus contenidos, ni que estos se encuentren actualizados, aunque tratar\u00e1 de realizar sus mayores esfuerzos para que, en su caso, se subsanen y se actualicen debidamente. One Eden Chiringuito no se responsabiliza de los da\u00f1os o perjuicios de cualquier tipo producidos en el usuario final a consecuencia de fallos o desconexiones en las redes de telecomunicaciones que produzcan la suspensi\u00f3n, cancelaci\u00f3n o interrupci\u00f3n del servicio del Sitio Web durante la prestaci\u00f3n del mismo o con car\u00e1cter previo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">One Eden Chiringuito excluye, con las excepciones contempladas en la normativa vigente, cualquier responsabilidad por los da\u00f1os y perjuicios de toda naturaleza que puedan deberse a la falta de disponibilidad, continuidad o calidad del funcionamiento del Sitio Web y de los contenidos, al no cumplir con la expectativa de utilidad que los usuarios hubieren podido atribuir al Sitio Web y a sus contenidos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La funci\u00f3n de los enlaces externos que aparecen en este Sitio Web es exclusivamente la de informar al usuario acerca de la existencia de otros Sitios Web, propiedad de One Eden Chiringuito, que contienen informaci\u00f3n sobre la materia.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El acceso al Sitio Web no implica la obligaci\u00f3n por parte de One Eden Chiringuito de controlar la ausencia de virus, gusanos o cualquier otro elemento inform\u00e1tico da\u00f1ino. Corresponde al usuario, en todo caso, la disponibilidad de herramientas adecuadas para la detecci\u00f3n y desinfecci\u00f3n de programas inform\u00e1ticos da\u00f1inos, por lo tanto, One Eden Chiringuito no se hace responsable de los posibles errores de seguridad que puedan producirse durante la prestaci\u00f3n del servicio del Sitio Web, ni de los posibles da\u00f1os que puedan causarse al sistema inform\u00e1tico del usuario o de terceros (hardware y software), los ficheros o documentos almacenados en el mismo, como consecuencia de la presencia de virus en el ordenador del usuario utilizado para la conexi\u00f3n a los servicios y contenidos del Sitio Web, de un mal funcionamiento del navegador o del uso de versiones no actualizadas del mismo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La informaci\u00f3n contenida en las p\u00e1ginas que componen este Sitio Web s\u00f3lo tiene car\u00e1cter informativo, consultivo, divulgativo y publicitario. En ning\u00fan caso ofrecen ni tienen car\u00e1cter de compromiso vinculante o contractual.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Limitaci\u00f3n de responsabilidad<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">One Eden Chiringuito excluye toda responsabilidad por las decisiones que el usuario final pueda tomar basado en esta informaci\u00f3n, as\u00ed como por los posibles errores tipogr\u00e1ficos que puedan contener los documentos y gr\u00e1ficos del Sitio Web. La informaci\u00f3n est\u00e1 sometida a posibles cambios peri\u00f3dicos sin previo aviso de su contenido por ampliaci\u00f3n, mejora, correcci\u00f3n o actualizaci\u00f3n de los contenidos.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Protecci\u00f3n de datos de car\u00e1cter personal<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">One Eden Chiringuito ha establecido una Pol\u00edtica de Protecci\u00f3n de Datos a fin de garantizar la m\u00e1xima seguridad en el tratamiento de los datos personales de los usuarios y con el objetivo de asegurar el cumplimiento de la legislaci\u00f3n vigente en esta materia.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Durante la navegaci\u00f3n a trav\u00e9s de la web <a href=\"http:\/\/www.oneedenchiringuito.com\">www.oneedenchiringuito.com<\/a> es posible que se soliciten datos de car\u00e1cter personal a trav\u00e9s de los formularios disponibles al efecto. Estos datos formar\u00e1n parte de los pertinentes tratamientos en funci\u00f3n de la finalidad concreta que legitima la recogida de los mismos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La informaci\u00f3n particular de cada tratamiento de datos se facilitar\u00e1 junto a cada formulario web, siendo com\u00fan a todos ellos el responsable del tratamiento: One Eden Chiringuito, as\u00ed como el lugar y forma de ejercicio de los derechos de acceso, rectificaci\u00f3n, supresi\u00f3n, portabilidad de sus datos, as\u00ed como de limitaci\u00f3n u oposici\u00f3n a su tratamiento, que deber\u00e1 formalizarse mediante una comunicaci\u00f3n escrita a la direcci\u00f3n indicada anteriormente incluyendo copia del DNI o documento identificativo equivalente.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En el supuesto de que aporte sus datos a trav\u00e9s de un mensaje de correo electr\u00f3nico, el mismo formar\u00e1 parte de un tratamiento cuya finalidad ser\u00e1 la gesti\u00f3n de la solicitud de informaci\u00f3n o comentario que nos realiza, siendo aplicables el resto de extremos indicados en el p\u00e1rrafo anterior.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Adem\u00e1s, One Eden Chiringuito ha implantado las medidas t\u00e9cnicas y organizativas necesarias para evitar la p\u00e9rdida, mal uso, alteraci\u00f3n, acceso no autorizado y robo de los Datos Personales que los interesados pudieran facilitar como consecuencia del acceso a las diferentes secciones del Sitio Web <a href=\"http:\/\/www.oneedenchiringuito.com\">www.oneedenchiringuito.com<\/a> aplicando las medidas de seguridad contempladas en el Reglamento (UE) 2016\/679 del Parlamento Europeo y del Consejo, de 27 de abril de 2016, relativo a la protecci\u00f3n de las personas f\u00edsicas en lo que respecta al tratamiento de datos personales y a la libre circulaci\u00f3n de estos datos.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Jurisdicci\u00f3n <\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Para cuantas cuestiones se susciten sobre la interpretaci\u00f3n, aplicaci\u00f3n y cumplimiento de estos T\u00e9rminos y Condiciones, as\u00ed como de las reclamaciones que puedan derivarse de su uso, todas las partes intervinientes se someten a los Jueces y Tribunales de M\u00e1laga, renunciando de forma expresa a cualquier otro fuero que pudiera corresponderles<\/p>\n","protected":false},"excerpt":{"rendered":"<p>En cumplimiento del deber de informaci\u00f3n estipulado en el art\u00edculo 10 de la Ley 34\/2002 de 11 de julio de Servicios de la Sociedad de la Informaci\u00f3n y de Comercio Electr\u00f3nico, One Eden Hotel &amp; Beach Club SL (en adelante, \u201cOne Eden Chiringuito\u201d) y en calidad de titular del Sitio Web www.oneedenchiringuito.com , procede a [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-232","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>T\u00e9rminos y condiciones - One Eden Chiringuito<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/oneedenchiringuito.com\/es\/terminos-y-condiciones\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"T\u00e9rminos y condiciones - One Eden Chiringuito\" \/>\n<meta property=\"og:description\" content=\"En cumplimiento del deber de informaci\u00f3n estipulado en el art\u00edculo 10 de la Ley 34\/2002 de 11 de julio de Servicios de la Sociedad de la Informaci\u00f3n y de Comercio Electr\u00f3nico, One Eden Hotel &amp; Beach Club SL (en adelante, \u201cOne Eden Chiringuito\u201d) y en calidad de titular del Sitio Web www.oneedenchiringuito.com , procede a [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/oneedenchiringuito.com\/es\/terminos-y-condiciones\/\" \/>\n<meta property=\"og:site_name\" content=\"One Eden Chiringuito\" \/>\n<meta property=\"article:modified_time\" content=\"2021-08-03T07:46:42+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"T\u00e9rminos y condiciones - One Eden Chiringuito","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/oneedenchiringuito.com\/es\/terminos-y-condiciones\/","og_locale":"es_ES","og_type":"article","og_title":"T\u00e9rminos y condiciones - One Eden Chiringuito","og_description":"En cumplimiento del deber de informaci\u00f3n estipulado en el art\u00edculo 10 de la Ley 34\/2002 de 11 de julio de Servicios de la Sociedad de la Informaci\u00f3n y de Comercio Electr\u00f3nico, One Eden Hotel &amp; Beach Club SL (en adelante, \u201cOne Eden Chiringuito\u201d) y en calidad de titular del Sitio Web www.oneedenchiringuito.com , procede a [&hellip;]","og_url":"https:\/\/oneedenchiringuito.com\/es\/terminos-y-condiciones\/","og_site_name":"One Eden Chiringuito","article_modified_time":"2021-08-03T07:46:42+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/oneedenchiringuito.com\/es\/terminos-y-condiciones\/","url":"https:\/\/oneedenchiringuito.com\/es\/terminos-y-condiciones\/","name":"T\u00e9rminos y condiciones - One Eden Chiringuito","isPartOf":{"@id":"https:\/\/oneedenchiringuito.com\/es\/#website"},"datePublished":"2021-08-02T18:02:32+00:00","dateModified":"2021-08-03T07:46:42+00:00","breadcrumb":{"@id":"https:\/\/oneedenchiringuito.com\/es\/terminos-y-condiciones\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/oneedenchiringuito.com\/es\/terminos-y-condiciones\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/oneedenchiringuito.com\/es\/terminos-y-condiciones\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/oneedenchiringuito.com\/es\/"},{"@type":"ListItem","position":2,"name":"T\u00e9rminos y condiciones"}]},{"@type":"WebSite","@id":"https:\/\/oneedenchiringuito.com\/es\/#website","url":"https:\/\/oneedenchiringuito.com\/es\/","name":"One Eden Chiringuito","description":"\u00c9rase un verano...","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/oneedenchiringuito.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"}]}},"_links":{"self":[{"href":"https:\/\/oneedenchiringuito.com\/es\/wp-json\/wp\/v2\/pages\/232","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/oneedenchiringuito.com\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/oneedenchiringuito.com\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/oneedenchiringuito.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/oneedenchiringuito.com\/es\/wp-json\/wp\/v2\/comments?post=232"}],"version-history":[{"count":1,"href":"https:\/\/oneedenchiringuito.com\/es\/wp-json\/wp\/v2\/pages\/232\/revisions"}],"predecessor-version":[{"id":233,"href":"https:\/\/oneedenchiringuito.com\/es\/wp-json\/wp\/v2\/pages\/232\/revisions\/233"}],"wp:attachment":[{"href":"https:\/\/oneedenchiringuito.com\/es\/wp-json\/wp\/v2\/media?parent=232"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}